{"id":248368,"date":"2026-02-10T12:45:20","date_gmt":"2026-02-10T11:45:20","guid":{"rendered":"https:\/\/tiendapadel5.com\/?post_type=product&#038;p=248368"},"modified":"2026-04-21T08:47:08","modified_gmt":"2026-04-21T06:47:08","slug":"wilson-optix-v2-power-red-2026","status":"publish","type":"product","link":"https:\/\/tiendapadel5.com\/pt-pt\/wilson-optix-v2-power-red-2026\/","title":{"rendered":"Wilson Optix V2 Power Red 2026"},"content":{"rendered":"<p>La pala de p\u00e1del Optix V2 Power de Wilson te ayuda a mantener el ritmo en los peloteos. Est\u00e1 dise\u00f1ada para jugadores ocasionales con experiencia en deportes de raqueta que buscan una pala que ofrezca potencia y comodidad. Dise\u00f1ada para una gran sensaci\u00f3n desde el primer momento, el marco de fibra de vidrio ofrece una combinaci\u00f3n de comodidad y capacidad de respuesta. El marco en forma de l\u00e1grima cuenta con un amplio punto dulce y ofrece una sensaci\u00f3n suave y c\u00f3moda al contacto.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"row\">\n<div class=\"col-xs-12\">\n<p><span dir=\"auto\">Una pala dise\u00f1ada para jugadores ocasionales, c\u00f3moda, con potencia y capacidad de respuesta.<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"row\"><\/div>\n","protected":false},"featured_media":248360,"comment_status":"open","ping_status":"closed","template":"","meta":{"ctx_rank_math_primary_category":"","_joinchat":[]},"pwb-brand":[37],"product_brand":[],"product_cat":[1860,11144,1942],"product_tag":[11591,10742,11589,1934,8093,1951,1947],"class_list":{"0":"post-248368","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-wilson","7":"product_cat-padel-rackets","8":"product_cat-2026-en","9":"product_cat-wilson-en","10":"product_tag-11591","11":"product_tag-optix","12":"product_tag-pala","13":"product_tag-power-en","14":"product_tag-red-en-2","15":"product_tag-v2-en","16":"product_tag-wilson-en","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-simple"},"brands":[{"id":37,"name":"Wilson","slug":"wilson"}],"_links":{"self":[{"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/product\/248368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=248368"}],"version-history":[{"count":2,"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/product\/248368\/revisions"}],"predecessor-version":[{"id":248370,"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/product\/248368\/revisions\/248370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/media\/248360"}],"wp:attachment":[{"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=248368"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/pwb-brand?post=248368"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=248368"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=248368"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tiendapadel5.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=248368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}